{"id":4429,"date":"2022-06-24T06:43:12","date_gmt":"2022-06-24T06:43:12","guid":{"rendered":"http:\/\/floramicato.com\/product\/fluffy-nyam-small"},"modified":"2026-06-30T14:30:54","modified_gmt":"2026-06-30T14:30:54","slug":"fluffy-nyam-small","status":"publish","type":"product","link":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small","title":{"rendered":"FLUFFY NYAM (SMALL)"},"content":{"rendered":"<p>Posebej oblikovana igra\u010da je narejena kot \u017eepek za hrano. Narejena je iz umetnega krzna in ima kraj\u0161i ro\u010daj. Ima dodatno plast materiala za trdnost. \u017depek za hrano pove\u010da \u017eeljo po igri.  <\/p>\n<p>\u017depek za hrano z dodatnim \u017eepom za piskalo 17 x 7 x 1,5 cm + 40 cm ro\u010daj.<\/p>\n<p>Odli\u010dnen za \u0161olanje in vle\u010denje manj\u0161ih srednje mo\u010dnih psov.<\/p>\n<p>Ni primerna za \u017eve\u010denje. Ko je igre konec, igra\u010do pospravite, da je pes ne bo dosegel. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Posebej oblikovana igra\u010da je narejena kot \u017eepek za hrano. Narejena je iz umetnega krzna in ima kraj\u0161i ro\u010daj.<\/p>\n","protected":false},"featured_media":3249,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[267,265],"product_tag":[],"class_list":{"0":"post-4429","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vlecenje","7":"product_cat-zepki-za-priboljske","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FLUFFY NYAM (SMALL) - Floramicato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small\" \/>\n<meta property=\"og:locale\" content=\"sl_SI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FLUFFY NYAM (SMALL) - Floramicato\" \/>\n<meta property=\"og:description\" content=\"Posebej oblikovana igra\u010da je narejena kot \u017eepek za hrano. Narejena je iz umetnega krzna in ima kraj\u0161i ro\u010daj.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small\" \/>\n<meta property=\"og:site_name\" content=\"Floramicato\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T14:30:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/floramicato.com\/wp-content\/uploads\/2022\/06\/nyam_S_purple_mint.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small\",\"url\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small\",\"name\":\"FLUFFY NYAM (SMALL) - Floramicato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/floramicato.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/floramicato.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nyam_S_purple_mint.jpg\",\"datePublished\":\"2022-06-24T06:43:12+00:00\",\"dateModified\":\"2026-06-30T14:30:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small#breadcrumb\"},\"inLanguage\":\"sl-SI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sl-SI\",\"@id\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small#primaryimage\",\"url\":\"https:\\\/\\\/floramicato.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nyam_S_purple_mint.jpg\",\"contentUrl\":\"https:\\\/\\\/floramicato.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/nyam_S_purple_mint.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelek\\\/fluffy-nyam-small#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/floramicato.com\\\/sl\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Izdelki\",\"item\":\"https:\\\/\\\/floramicato.com\\\/sl\\\/izdelki\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FLUFFY NYAM (SMALL)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/floramicato.com\\\/#website\",\"url\":\"https:\\\/\\\/floramicato.com\\\/\",\"name\":\"Floramicato\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/floramicato.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sl-SI\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FLUFFY NYAM (SMALL) - Floramicato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small","og_locale":"sl_SI","og_type":"article","og_title":"FLUFFY NYAM (SMALL) - Floramicato","og_description":"Posebej oblikovana igra\u010da je narejena kot \u017eepek za hrano. Narejena je iz umetnega krzna in ima kraj\u0161i ro\u010daj.","og_url":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small","og_site_name":"Floramicato","article_modified_time":"2026-06-30T14:30:54+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/floramicato.com\/wp-content\/uploads\/2022\/06\/nyam_S_purple_mint.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small","url":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small","name":"FLUFFY NYAM (SMALL) - Floramicato","isPartOf":{"@id":"https:\/\/floramicato.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small#primaryimage"},"image":{"@id":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small#primaryimage"},"thumbnailUrl":"https:\/\/floramicato.com\/wp-content\/uploads\/2022\/06\/nyam_S_purple_mint.jpg","datePublished":"2022-06-24T06:43:12+00:00","dateModified":"2026-06-30T14:30:54+00:00","breadcrumb":{"@id":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small#breadcrumb"},"inLanguage":"sl-SI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small"]}]},{"@type":"ImageObject","inLanguage":"sl-SI","@id":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small#primaryimage","url":"https:\/\/floramicato.com\/wp-content\/uploads\/2022\/06\/nyam_S_purple_mint.jpg","contentUrl":"https:\/\/floramicato.com\/wp-content\/uploads\/2022\/06\/nyam_S_purple_mint.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/floramicato.com\/sl\/izdelek\/fluffy-nyam-small#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/floramicato.com\/sl"},{"@type":"ListItem","position":2,"name":"Izdelki","item":"https:\/\/floramicato.com\/sl\/izdelki"},{"@type":"ListItem","position":3,"name":"FLUFFY NYAM (SMALL)"}]},{"@type":"WebSite","@id":"https:\/\/floramicato.com\/#website","url":"https:\/\/floramicato.com\/","name":"Floramicato","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/floramicato.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sl-SI"}]}},"_links":{"self":[{"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/product\/4429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/comments?post=4429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/media\/3249"}],"wp:attachment":[{"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/media?parent=4429"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/product_brand?post=4429"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/product_cat?post=4429"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/floramicato.com\/sl\/wp-json\/wp\/v2\/product_tag?post=4429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}